{"id":279,"date":"2007-09-14T09:10:21","date_gmt":"2007-09-14T09:10:21","guid":{"rendered":"https:\/\/dreamlions.ch\/en-pointe\/?p=279"},"modified":"2020-10-24T08:38:41","modified_gmt":"2020-10-24T08:38:41","slug":"the-beginning","status":"publish","type":"post","link":"https:\/\/dreamlions.ch\/en-pointe\/2007\/09\/14\/the-beginning\/","title":{"rendered":"The beginning"},"content":{"rendered":"\n<p>Heute, am 14.09.2007 um 09.10 Uhr habe ich das Licht der Welt erblickt. Man sagt, dass das Leben bereits vorbestimmt ist und wir genau dies erleben und durchleben, was f\u00fcr uns bestimmt ist.<\/p>\n\n\n\n<p>Nun ja, dann w\u00e4re ja meine Wegbestimmung aktuell ganz klar: die Liebe zum Ballett und zum N\u00e4hen.<\/p>\n\n\n\n<p>Aus diesem Grund ist an meinem 13. Geburtstag, also am 14.09.2020 diese Homepage geboren.<\/p>\n\n\n\n<p>Danke, dass ich meine Freude mit dir teilen darf&#8230;<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute, am 14.09.2007 um 09.10 Uhr habe ich das Licht der Welt erblickt. Man sagt, dass das Leben bereits vorbestimmt ist und wir genau dies&hellip; <\/p>\n","protected":false},"author":3,"featured_media":280,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,28,24],"tags":[17],"class_list":["post-279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ballett","category-gallery","category-naehen","tag-ballett"],"_links":{"self":[{"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/posts\/279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/comments?post=279"}],"version-history":[{"count":1,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/posts\/279\/revisions"}],"predecessor-version":[{"id":281,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/posts\/279\/revisions\/281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/media?parent=279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/categories?post=279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dreamlions.ch\/en-pointe\/wp-json\/wp\/v2\/tags?post=279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}